{"id":69210,"date":"2023-10-09T07:45:19","date_gmt":"2023-10-09T05:45:19","guid":{"rendered":"https:\/\/www.metalfach.com.pl\/produits\/remorques-agricoles\/przyczepa-rolnicza-dwuosiowa-t739-long\/"},"modified":"2024-06-17T19:04:32","modified_gmt":"2024-06-17T17:04:32","slug":"remorque-agricole-a-deux-essieux-t739-long","status":"publish","type":"page","link":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/","title":{"rendered":"Remorque agricole \u00e0 deux essieux T739 LONG"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"69210\" class=\"elementor elementor-69210 elementor-62666\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a71fe71 elementor-section-height-min-height elementor-section-full_width elementor-section-content-middle elementor-section-items-bottom elementor-section-height-default\" data-id=\"a71fe71\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fb9898\" data-id=\"6fb9898\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa64cac elementor-widget elementor-widget-heading\" data-id=\"aa64cac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Flexibilit\u00e9 de chargement et de d\u00e9chargement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b73417\" data-id=\"5b73417\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c28c3a elementor-section-full_width elementor-section-content-middle elementor-hidden-phone elementor-hidden-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"6c28c3a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f66d81c\" data-id=\"f66d81c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de7bd5b elementor-widget elementor-widget-heading\" data-id=\"de7bd5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">T739AL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cffbd90\" data-id=\"cffbd90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18319c8 elementor-nav-menu__align-start elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"18319c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-grow\">\n\t\t\t\t<ul id=\"menu-1-18319c8\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32153\"><a href=\"#densemble\" class=\"elementor-item elementor-item-anchor\">Vue d\u2019ensemble<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32154\"><a href=\"#caracteristiques\" class=\"elementor-item elementor-item-anchor\">Caract\u00e9ristiques sp\u00e9cifiques<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32155\"><a href=\"#specification\" class=\"elementor-item elementor-item-anchor\">Sp\u00e9cification technique<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32156\"><a href=\"#multimedia\" class=\"elementor-item elementor-item-anchor\">Multim\u00e9dia<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32157\"><a href=\"#telecharger\" class=\"elementor-item elementor-item-anchor\">Fichiers \u00e0 t\u00e9l\u00e9charger<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-18319c8\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32153\"><a href=\"#densemble\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Vue d\u2019ensemble<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32154\"><a href=\"#caracteristiques\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Caract\u00e9ristiques sp\u00e9cifiques<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32155\"><a href=\"#specification\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Sp\u00e9cification technique<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32156\"><a href=\"#multimedia\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Multim\u00e9dia<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-32157\"><a href=\"#telecharger\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Fichiers \u00e0 t\u00e9l\u00e9charger<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d3b565f elementor-hidden-phone\" data-id=\"d3b565f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3e9d11d elementor-hidden-phone\" data-id=\"3e9d11d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c949826 elementor-section-full_width elementor-section-content-middle elementor-section-stretched elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"c949826\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9fb9c40\" data-id=\"9fb9c40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e61eb4e elementor-widget elementor-widget-heading\" data-id=\"e61eb4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">T739AL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2b7ff2d\" data-id=\"2b7ff2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e4e814 elementor-hidden-phone\" data-id=\"0e4e814\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c04dbf6 elementor-section-content-middle breadcrumbs_seo elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c04dbf6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a0af4fc\" data-id=\"a0af4fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70b4806 elementor-widget elementor-widget-text-editor\" data-id=\"70b4806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span><span><a href=\"https:\/\/www.metalfach.com.pl\/fr\/\">Accueil<\/a><\/span><\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-321886e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"321886e\" data-element_type=\"section\" data-e-type=\"section\" id=\"densemble\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de6e419\" data-id=\"de6e419\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-634e891 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"634e891\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63135bc\" data-id=\"63135bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76c5c6e active1 elementor-widget elementor-widget-image\" data-id=\"76c5c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp\" class=\"attachment-full size-full wp-image-62656\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp 660w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371-480x270.webp 480w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3e997a3\" data-id=\"3e997a3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d17c041 active1 elementor-widget elementor-widget-image\" data-id=\"d17c041\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long-tyl_660x371.webp\" class=\"attachment-full size-full wp-image-62662\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long-tyl_660x371.webp 660w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long-tyl_660x371-480x270.webp 480w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b64980b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b64980b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bf8ebb2\" data-id=\"bf8ebb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20140eb elementor-widget elementor-widget-text-editor\" data-id=\"20140eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PTAC<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0fffdcb elementor-widget elementor-widget-text-editor\" data-id=\"0fffdcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>18 000 kg<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-95a3597\" data-id=\"95a3597\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-212ee3c elementor-widget elementor-widget-text-editor\" data-id=\"212ee3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Charge utile<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53518dc elementor-widget elementor-widget-text-editor\" data-id=\"53518dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>14 000 kg<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-14b2269\" data-id=\"14b2269\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaa205d elementor-widget elementor-widget-text-editor\" data-id=\"aaa205d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Capacit\u00e9<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da1672d elementor-widget elementor-widget-text-editor\" data-id=\"da1672d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>7,8 m<sup>3<\/sup><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-41dfd6e elementor-section-height-min-height elementor-section-content-top elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"41dfd6e\" data-element_type=\"section\" data-e-type=\"section\" id=\"caracteristiques\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5a2a197\" data-id=\"5a2a197\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a0c0df elementor-widget elementor-widget-image\" data-id=\"8a0c0df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-niedzielone-burty.webp\" class=\"attachment-full size-full wp-image-62626\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-niedzielone-burty.webp 1200w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-niedzielone-burty-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-niedzielone-burty-480x320.webp 480w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85cc116 elementor-widget elementor-widget-text-editor\" data-id=\"85cc116\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fae62a4\" data-id=\"fae62a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be6ea5b elementor-widget elementor-widget-image\" data-id=\"be6ea5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-uszczelnienie-burt.webp\" class=\"attachment-full size-full wp-image-62032\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-uszczelnienie-burt.webp 800w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-uszczelnienie-burt-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-uszczelnienie-burt-480x320.webp 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7f89d elementor-widget elementor-widget-text-editor\" data-id=\"1f7f89d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les joints des ridelles de la remorque agricole T739AL prot\u00e8gent solidement la charge contre les chutes pendant le transport.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-85d0ea0\" data-id=\"85d0ea0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9616c1 elementor-widget elementor-widget-image\" data-id=\"d9616c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-lancuchy-spinajace-sciany.webp\" class=\"attachment-full size-full wp-image-62632\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-lancuchy-spinajace-sciany.webp 1200w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-lancuchy-spinajace-sciany-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-przyczepa-burtowa-dwuosiowa-t739al-long-lancuchy-spinajace-sciany-480x320.webp 480w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39f550d elementor-widget elementor-widget-text-editor\" data-id=\"39f550d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les cha\u00eenes de serrage des parois sont une solution fiable qui permet de renforcer les parois du compartiment de chargement, facilitant le transport et prot\u00e9geant votre cargaison.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-ce17654 elementor-section-height-min-height elementor-section-content-top elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"ce17654\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-209c5fd\" data-id=\"209c5fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecbb371 elementor-widget elementor-widget-image\" data-id=\"ecbb371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-system-ryglowania-scian.webp\" class=\"attachment-full size-full wp-image-62311\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-system-ryglowania-scian.webp 1200w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-system-ryglowania-scian-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-burtowa-t940-wywrotka-system-ryglowania-scian-480x320.webp 480w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83f8a3 elementor-widget elementor-widget-text-editor\" data-id=\"a83f8a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le syst\u00e8me de verrouillage de la paroi centrale au bord du plancher des remorques \u00e0 ridelles assure une fermeture rapide et s\u00fbre du compartiment de chargement.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4684ab7\" data-id=\"4684ab7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79f8478 elementor-widget elementor-widget-image\" data-id=\"79f8478\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"799\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739a-wywrotka-szerokosc-paletowa.webp\" class=\"attachment-full size-full wp-image-62650\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739a-wywrotka-szerokosc-paletowa.webp 1200w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739a-wywrotka-szerokosc-paletowa-768x511.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739a-wywrotka-szerokosc-paletowa-480x320.webp 480w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7886326 elementor-widget elementor-widget-text-editor\" data-id=\"7886326\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La remorque \u00e0 ridelles T739AL permet de transporter des charges sur des Europalettes, ce qui accro\u00eet sa fonctionnalit\u00e9 et sa flexibilit\u00e9 pour diverses applications de transport. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4066416\" data-id=\"4066416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99118fa elementor-widget elementor-widget-image\" data-id=\"99118fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie.webp\" class=\"attachment-full size-full wp-image-61929\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie.webp 800w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie-480x320.webp 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f34cd8d elementor-widget elementor-widget-text-editor\" data-id=\"f34cd8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La face arri\u00e8re est \u00e9quip\u00e9e d\u2019une porte coulissante avec une goulotte \u2013 ce qui vous permet de r\u00e9gler avec pr\u00e9cision le flux de mat\u00e9riaux pour un d\u00e9chargement facile et efficace de votre r\u00e9colte.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-824268e elementor-section-height-min-height elementor-section-content-top elementor-section-items-top elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default\" data-id=\"824268e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b292f8d\" data-id=\"b292f8d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd673bb elementor-widget elementor-widget-image\" data-id=\"dd673bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepy-burtowe-wywrotki-dwuosiowe-t711-t710-podlaczenie-do-drugiej-przyczepy-tylne-wyjscia-hydrauliki.webp\" class=\"attachment-full size-full wp-image-62415\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepy-burtowe-wywrotki-dwuosiowe-t711-t710-podlaczenie-do-drugiej-przyczepy-tylne-wyjscia-hydrauliki.webp 1200w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepy-burtowe-wywrotki-dwuosiowe-t711-t710-podlaczenie-do-drugiej-przyczepy-tylne-wyjscia-hydrauliki-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepy-burtowe-wywrotki-dwuosiowe-t711-t710-podlaczenie-do-drugiej-przyczepy-tylne-wyjscia-hydrauliki-480x320.webp 480w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aabc45 elementor-widget elementor-widget-text-editor\" data-id=\"7aabc45\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019\u00e9quipement standard de la s\u00e9rie T711L de remorques \u00e0 ridelles avec un syst\u00e8me hydraulique et \u00e9lectrique pour une deuxi\u00e8me remorque offre la commodit\u00e9 et la possibilit\u00e9 de transporter une charge suppl\u00e9mentaire, ce qui se traduit par une plus grande efficacit\u00e9 et un gain de temps dans vos op\u00e9rations agricoles.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bc48734\" data-id=\"bc48734\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-922f5e9 elementor-widget elementor-widget-image\" data-id=\"922f5e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/oswietlenie-led-przyczepy-burtowe.webp\" class=\"attachment-full size-full wp-image-61909\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/oswietlenie-led-przyczepy-burtowe.webp 800w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/oswietlenie-led-przyczepy-burtowe-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/oswietlenie-led-przyczepy-burtowe-480x320.webp 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33a2564 elementor-widget elementor-widget-text-editor\" data-id=\"33a2564\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019\u00e9clairage LED contribue \u00e0 une faible consommation<br \/>d\u2019\u00e9nergie, ce qui prolonge la dur\u00e9e de vie de la batterie et am\u00e9liore l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f1ad177 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"f1ad177\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-616208c elementor-widget elementor-widget-image\" data-id=\"616208c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie.webp\" class=\"attachment-full size-full wp-image-61929\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie.webp 800w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie-768x512.webp 768w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/szyber-zsypowy-z-rynna-nowe-rozwiazanie-480x320.webp 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af9e7fa elementor-widget elementor-widget-text-editor\" data-id=\"af9e7fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La face arri\u00e8re est \u00e9quip\u00e9e d\u2019une porte coulissante avec une goulotte \u2013 ce qui vous permet de r\u00e9gler avec pr\u00e9cision le flux de mat\u00e9riaux pour un d\u00e9chargement facile et efficace de votre r\u00e9colte.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53e0ba0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"53e0ba0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d28b29\" data-id=\"0d28b29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b854a1e elementor-widget elementor-widget-heading\" data-id=\"b854a1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personnalisez<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3c37f8 elementor-widget elementor-widget-heading\" data-id=\"d3c37f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comparez et choisissez la couleur de la remorque<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-14919d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14919d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2406427\" data-id=\"2406427\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ded1d69 elementor-widget elementor-widget-text-editor\" data-id=\"ded1d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019\u00e9quipement montr\u00e9 sur les photos peut varier selon la version choisie.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d447a9d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d447a9d\" data-element_type=\"section\" data-e-type=\"section\" id=\"specification\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e9184f\" data-id=\"9e9184f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e54a80 elementor-widget elementor-widget-heading\" data-id=\"1e54a80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sp\u00e9cification technique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e533495 elementor-widget elementor-widget-text-editor\" data-id=\"e533495\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les donn\u00e9es techniques du produit s\u00e9lectionn\u00e9 (y compris le poids \/ la capacit\u00e9 de charge) peuvent varier en fonction de l\u2019\u00e9quipement choisi.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9bbdc5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bbdc5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-84ee910\" data-id=\"84ee910\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-098d830 elementor-widget elementor-widget-heading\" data-id=\"098d830\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00c9quipement standard <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6f4cdb elementor-widget elementor-widget-text-editor\" data-id=\"c6f4cdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"list-stand\">\n<li>Ridelle renforc\u00e9e par un profil\u00e9 \u2013 sans poteau central<\/li>\n<li>Hauteur de la ridelle 600 mm<\/li>\n<li>Syst\u00e8me central de verrouillage des parois<\/li>\n<li>Cha\u00eene de serrage des parois<\/li>\n<li>Porte coulissante avec goulotte<\/li>\n<li>\u00c9chelle<\/li>\n<li>Timon d\u2019attelage type V 2000 + anneau d\u2019attelage \u03a6 40 mm<\/li>\n<li>Syst\u00e8me hydraulique et \u00e9lectrique pour la deuxi\u00e8me remorque<\/li>\n<li>Frein pneumatique \u00e0 2 fils avec connexion pour la deuxi\u00e8me remorque<\/li>\n<li>Pneumatiques 385\/65 R22,5 (reconditionn\u00e9s)<\/li>\n<li>Cales de roues, 2 pcs<\/li>\n<li>\u00c9clairage LED<\/li>\n<li>Garde-boues en plastique 4 pcs.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-75d65d9\" data-id=\"75d65d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15848ba elementor-widget elementor-widget-heading\" data-id=\"15848ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00c9quipement en option<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00fdad4 elementor-widget elementor-widget-text-editor\" data-id=\"00fdad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul class=\"list-opt\">\n<li>Ridelle inf\u00e9rieure 800 mm \u2013 disponible moyennant un suppl\u00e9ment de prix<\/li>\n<li>Ensemble du ressort de pression de la ridelle avant<\/li>\n<li>Rehausse pleine avec joint d\u2019\u00e9tanch\u00e9it\u00e9 de 600 mm (pour ridelle inf\u00e9rieure 800 mm)<\/li>\n<li>Rehausse pleine avec joint d\u2019\u00e9tanch\u00e9it\u00e9 de 800 mm (pour ridelle inf\u00e9rieure 600 mm)<\/li>\n<li>B\u00e2che tendue sur structure d\u00e9montable<\/li>\n<li>Plate-forme de travail avec garde-corps \u2013 disponible moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Timon type V allong\u00e9 (2200 mm) \u2013 disponible moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Timon type Y (2100 mm) \u2013 disponible moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Timon type Y allong\u00e9 (2350 mm) \u2013 disponible moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Timon de type V (2000 mm) fi 40 renforc\u00e9 \u2013 disponible moyennant un suppl\u00e9ment de prix<\/li>\n<li>Anneau d\u2019attelage \u03a650mm pour timon type Y disponible moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Attelage automatique arri\u00e8re \u2013 disponible moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Frein de stationnement \u00e0 ressort et \u00e0 membrane \u2013 disponible moyennant un suppl\u00e9ment de prix<\/li>\n<li>Syst\u00e8me de r\u00e9glage automatique de la force de freinage, vanne ALB<\/li>\n<li>Roues 385\/65 R22,5 (neuves) \u2013 disponibles moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Roues 550\/45-22,5 \u2013 disponibles moyennant un suppl\u00e9ment de prix*<\/li>\n<li>Panier \u00e0 roue de secours et cric<\/li>\n<li>Roue de secours \u2013 (385\/65 R22,5)<\/li>\n<li>Roue de secours \u2013 reconditionn\u00e9e (385\/65 R22,5)<\/li>\n<li>Roue de secours \u2013 550\/45-22,5<\/li>\n<li>R\u00e9servoir d\u2019eau avec doseur de savon<\/li>\n<li>Boite \u00e0 outils en plastique<\/li>\n<li>Protections lat\u00e9rales pare-cycliste<\/li>\n<li>Suppl\u00e9ment pour l\u2019homologation UE<\/li>\n<li>Peinture du bo\u00eetier dans une couleur diff\u00e9rente de la couleur standard \u2013 disponible moyennant un suppl\u00e9ment de prix<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e8b65e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e8b65e\" data-element_type=\"section\" data-e-type=\"section\" id=\"multimedia\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45bc6d6\" data-id=\"45bc6d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0764879 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0764879\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15c98e9\" data-id=\"15c98e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46378cd elementor-widget elementor-widget-heading\" data-id=\"46378cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Galerie de photos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78bcab4 elementor-widget elementor-widget-heading\" data-id=\"78bcab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T739AL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c2d6e02\" data-id=\"c2d6e02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb64834 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"eb64834\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;speed&quot;:1000,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-14t.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eb64834\" data-elementor-lightbox-title=\"przyczepa-rolnicza-dwuosiowa-T739-14t\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE0OTksInVybCI6Imh0dHBzOlwvXC93d3cubWV0YWxmYWNoLmNvbS5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvcHJ6eWN6ZXBhLXJvbG5pY3phLWR3dW9zaW93YS10NzM5LTE0dC53ZWJwIiwic2xpZGVzaG93IjoiZWI2NDgzNCJ9\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-rolnicza-dwuosiowa-T739-14t\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-14t.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-przod.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eb64834\" data-elementor-lightbox-title=\"przyczepa-rolnicza-dwuosiowa-T739-przod\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1MDUsInVybCI6Imh0dHBzOlwvXC93d3cubWV0YWxmYWNoLmNvbS5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvcHJ6eWN6ZXBhLXJvbG5pY3phLWR3dW9zaW93YS10NzM5LXByem9kLndlYnAiLCJzbGlkZXNob3ciOiJlYjY0ODM0In0%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-rolnicza-dwuosiowa-T739-przod\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-przod.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-wewnatrz-skrzyni.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"eb64834\" data-elementor-lightbox-title=\"przyczepa-rolnicza-dwuosiowa-T739-wewnatrz-skrzyni\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTE1MTEsInVybCI6Imh0dHBzOlwvXC93d3cubWV0YWxmYWNoLmNvbS5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvcHJ6eWN6ZXBhLXJvbG5pY3phLWR3dW9zaW93YS10NzM5LXdld25hdHJ6LXNrcnp5bmkud2VicCIsInNsaWRlc2hvdyI6ImViNjQ4MzQifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-rolnicza-dwuosiowa-T739-wewnatrz-skrzyni\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-wewnatrz-skrzyni.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Diapositives Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-rolnicza-dwuosiowa-T739-14t\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-14t.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-rolnicza-dwuosiowa-T739-przod\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-przod.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-rolnicza-dwuosiowa-T739-wewnatrz-skrzyni\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-t739-wewnatrz-skrzyni.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e1cec1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e1cec1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec9f1b3\" data-id=\"ec9f1b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-823ea3b elementor-widget elementor-widget-heading\" data-id=\"823ea3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vid\u00e9o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef5f1af elementor-widget elementor-widget-heading\" data-id=\"ef5f1af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T739AL<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8bc1d10\" data-id=\"8bc1d10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d3c1e7 elementor-pagination-type-progressbar elementor-pagination-position-inside elementor-skin-carousel elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"0d3c1e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination&quot;:&quot;progressbar&quot;,&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;loop&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Diapositives\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-t710-v.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0d3c1e7\" data-elementor-lightbox-title=\"przyczepa-T710-v\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NTEyNzcsInVybCI6Imh0dHBzOlwvXC93d3cubWV0YWxmYWNoLmNvbS5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvcHJ6eWN6ZXBhLXQ3MTAtdi53ZWJwIiwic2xpZGVzaG93IjoiMGQzYzFlNyJ9\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/qzdn39kHn7c?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"przyczepa-T710-v\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-t710-v.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Lire<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/2022\/05\/playlista-przyczepy-rolnicze.webp\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0d3c1e7\" data-elementor-lightbox-title=\"playlista-przyczepy-rolnicze\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDM1NDMsInVybCI6Imh0dHBzOlwvXC93d3cubWV0YWxmYWNoLmNvbS5wbFwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMlwvMDVcL3BsYXlsaXN0YS1wcnp5Y3plcHktcm9sbmljemUud2VicCIsInNsaWRlc2hvdyI6IjBkM2MxZTcifQ%3D%3D\" data-elementor-lightbox-video=\"https:\/\/www.youtube.com\/embed\/KNTEuc7L-8c?feature=oembed&amp;autoplay=1&amp;rel=0&amp;controls=0\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Przyczepy rolnicze\" style=\"background-image: url(&#039;https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/2022\/05\/playlista-przyczepy-rolnicze.webp&#039;)\">\n\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\">\n\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Lire<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00e9c\u00e9dent\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Suivant\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-564f669 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"564f669\" data-element_type=\"section\" data-e-type=\"section\" id=\"telecharger\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3e25f4c\" data-id=\"3e25f4c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c75abd elementor-widget elementor-widget-heading\" data-id=\"9c75abd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fichiers \u00e0 t\u00e9l\u00e9charger<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0c6329 elementor-widget elementor-widget-heading\" data-id=\"c0c6329\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9l\u00e9charger les documents<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-388deee elementor-widget elementor-widget-spacer\" data-id=\"388deee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c6a7d4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6c6a7d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-337e0ea\" data-id=\"337e0ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-655b9c0 elementor-widget elementor-widget-template\" data-id=\"655b9c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"49405\" class=\"elementor elementor-49405 elementor-46917 elementor-46917\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-cd0c2e5 e-con-full e-flex e-con e-parent\" data-id=\"cd0c2e5\" data-element_type=\"container\" data-e-type=\"container\" id=\"cta-efficiency\">\n\t\t<div class=\"elementor-element elementor-element-af36aec e-con-full e-flex e-con e-child\" data-id=\"af36aec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2562feb e-con-full e-flex e-con e-child\" data-id=\"2562feb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c87e53 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4c87e53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Efficacit\u00e9 \u00e0 chaque hectare<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da8ea2b elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"da8ea2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Nous fournissons des solutions utiles et fonctionnelles qui r\u00e9pondent \u00e0 vos besoins sp\u00e9cifiques et vous aident \u00e0 obtenir de meilleurs r\u00e9sultats dans vos travaux agricoles.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e72ca7 elementor-widget elementor-widget-off-canvas\" data-id=\"2e72ca7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;entrance_animation&quot;:&quot;slideInUp&quot;,&quot;exit_animation&quot;:&quot;slideInUp&quot;,&quot;prevent_scroll&quot;:&quot;yes&quot;}\" data-widget_type=\"off-canvas.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"off-canvas-2e72ca7\" class=\"e-off-canvas\" role=\"dialog\" aria-hidden=\"true\" aria-label=\"\u00c9crivez-nous CTA\" aria-modal=\"true\" inert=\"\" data-delay-child-handlers=\"true\">\n\t\t\t<div class=\"e-off-canvas__overlay\"><\/div>\n\t\t\t<div class=\"e-off-canvas__main\">\n\t\t\t\t<div class=\"e-off-canvas__content\">\n\t\t\t\t\t<div class=\"elementor-element elementor-element-ca084c3 e-con-full e-flex e-con e-child\" data-id=\"ca084c3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e58c539 e-con-full e-flex e-con e-child\" data-id=\"e58c539\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e58b98 elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"5e58b98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action%3Aaction%3Doff_canvas%3Aclose%26settings%3DeyJpZCI6IjJlNzJjYTciLCJkaXNwbGF5TW9kZSI6ImNsb3NlIn0%3D\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" width=\"683.76px\" height=\"422.377px\" viewBox=\"-130.691 603.168 683.76 422.377\" xml:space=\"preserve\"><path d=\"M374.884,652.076c7.811,7.811,7.811,20.473,0,28.283L77.192,978.052c-7.811,7.812-20.474,7.812-28.285,0.001l-1.414-1.415 c-7.81-7.81-7.811-20.474,0-28.284l297.692-297.692c7.813-7.812,20.475-7.81,28.285,0L374.884,652.076z\"><\/path><path d=\"M373.47,978.052c-7.811,7.812-20.473,7.812-28.284,0L47.493,680.36c-7.811-7.811-7.812-20.473,0-28.284l1.414-1.415 c7.81-7.809,20.474-7.811,28.285,0.001l297.691,297.692c7.812,7.811,7.811,20.475,0,28.283L373.47,978.052z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d942e40 elementor-widget elementor-widget-template\" data-id=\"d942e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"32158\" class=\"elementor elementor-32158 elementor-23331 elementor-23331 elementor-23331\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-dcfcfe2 e-con-full e-flex e-con e-parent\" data-id=\"dcfcfe2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7b9be0a e-con-full e-flex e-con e-child\" data-id=\"7b9be0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a327893 elementor-widget elementor-widget-heading\" data-id=\"a327893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Demandez une offre personnalis\u00e9e<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d50b09f elementor-widget elementor-widget-heading\" data-id=\"d50b09f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Remplissez le formulaire et notre conseiller vous contactera dans les plus brefs d\u00e9lais. <br>Veuillez remplir tous les champs marqu\u00e9s *.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0043db elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"f0043db\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Dos&quot;,&quot;step_type&quot;:&quot;text&quot;,&quot;button_width&quot;:&quot;100&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" id=\"order_offer\" name=\"zamow-oferte-FR\" aria-label=\"zamow-oferte-FR\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"32158\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"f0043db\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Metal-Fach\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-step1 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 1 \" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-kraj elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-kraj\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmplacement\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[kraj]\" id=\"form-field-kraj\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Entrez le pays *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-step2 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 2\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-radio elementor-field-group elementor-column elementor-field-group-pan elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-pan\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tRemplissez le formulaire avec vos coordonn\u00e9es\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  elementor-subgroup-inline\"><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Monsieur \" id=\"form-field-pan-0\" name=\"form_fields[pan]\" required=\"required\"> <label for=\"form-field-pan-0\">Monsieur <\/label><\/span><span class=\"elementor-field-option\"><input type=\"radio\" value=\"Madame\" id=\"form-field-pan-1\" name=\"form_fields[pan]\" required=\"required\"> <label for=\"form-field-pan-1\">Madame<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-imie elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[imie]\" id=\"form-field-imie\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom et pr\u00e9nom *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-mail *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-nr_tel elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[nr_tel]\" id=\"form-field-nr_tel\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-step3 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 3\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-ulica elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[ulica]\" id=\"form-field-ulica\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Rue, num\u00e9ro de maison\/appartement *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-lokalizacja elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[lokalizacja]\" id=\"form-field-lokalizacja\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Ville *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-kod_pocztowy elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[kod_pocztowy]\" id=\"form-field-kod_pocztowy\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Code postal *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-woj elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[woj]\" id=\"form-field-woj\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"R\u00e9gion *\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-step4 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 4\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-wielkosc_gospodarstwa elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-wielkosc_gospodarstwa\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTaille de l'exploitation agricole\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[wielkosc_gospodarstwa]\" id=\"form-field-wielkosc_gospodarstwa\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"jusqu&#039;\u00e0 50\">jusqu&#039;\u00e0 50<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"50-150\">50-150<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"150-300\">150-300<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"plus de 300\">plus de 300<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-profil elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-profil\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tProfil de production agricole\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[profil]\" id=\"form-field-profil\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_5c8347d elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 5\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-zainteresowany elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-zainteresowany\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tQu'est-ce qui vous int\u00e9resse ? \t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[zainteresowany]\" id=\"form-field-zainteresowany\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"Offre de prix\">Offre de prix<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Plus d&#039;informations\">Plus d&#039;informations<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-step5 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 6\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-produkt elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-produkt\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tLe produit vous int\u00e9resse ?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[produkt]\" id=\"form-field-produkt\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"Presses \u00e0 balles\">Presses \u00e0 balles<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Enrubanneuses de balles\">Enrubanneuses de balles<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Chargeurs\">Chargeurs<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Accessoires pour chargeurs\">Accessoires pour chargeurs<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Remorques m\u00e9langeuses\">Remorques m\u00e9langeuses<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"\u00c9pandeurs \u00e0 fumier\">\u00c9pandeurs \u00e0 fumier<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Remorques \u00e0 ridelles\">Remorques \u00e0 ridelles<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Remorques monocoques\">Remorques monocoques<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Remorques de chantier\">Remorques de chantier<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Remorques volum\u00e9triques \u00e0 paroi coulissante\">Remorques volum\u00e9triques \u00e0 paroi coulissante<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Remorques pour balles\">Remorques pour balles<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Machines de travail du sol\">Machines de travail du sol<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Faucheuses\">Faucheuses<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Balayeuses\">Balayeuses<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Andaineuses\">Andaineuses<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-model elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-model\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tMod\u00e8le de machine\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[model]\" id=\"form-field-model\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"\"><\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-uwagi elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-uwagi\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCommentaires ou demandes suppl\u00e9mentaires\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[uwagi]\" id=\"form-field-uwagi\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-step6 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\u00c9tape 7\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_643f7cc elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_643f7cc\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tPolitique de confidentialit\u00e9 \u2013 Consentements\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_643f7cc]\" id=\"form-field-field_643f7cc\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_643f7cc\">Je d\u00e9clare consentir au traitement de mes donn\u00e9es \u00e0 caract\u00e8re personnel fournies \u00e0 METAL-FACH Sp. z o.o. dans ce formulaire afin de recevoir des documents marketing (y compris des calendriers, des gadgets publicitaires, etc.) METAL-FACH Sp. z o.o. par courrier \u00e0 l\u2019adresse indiqu\u00e9e ci-dessus.  <\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-oswiadczenie_2 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[oswiadczenie_2]\" id=\"form-field-oswiadczenie_2\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-oswiadczenie_2\">Je d\u00e9clare consentir \u00e0 recevoir des informations commerciales et des contenus marketing de METAL-FACH Sp. z o.o. (y compris les nouveaux produits, services et concours) au num\u00e9ro de t\u00e9l\u00e9phone indiqu\u00e9 ci-dessus. Je consens au traitement de mes donn\u00e9es \u00e0 caract\u00e8re personnel fournies \u00e0 METAL-FACH Sp. z o.o. dans ce formulaire.   <\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-oswiadczenie_3 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[oswiadczenie_3]\" id=\"form-field-oswiadczenie_3\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-oswiadczenie_3\">Je d\u00e9clare consentir au traitement de mes donn\u00e9es \u00e0 caract\u00e8re personnel fournies \u00e0 METAL-FACH Sp. z o.o. dans ce formulaire dans le but de recevoir des documents marketing \/ commerciaux de METAL-FACH Sp. z o.o. et de recevoir de METAL-FACH Sp. z o.o. par voie \u00e9lectronique \u00e0 l\u2019adresse e-mail fournie dans le formulaire, des informations commerciales \/ marketing sur les activit\u00e9s de cette entit\u00e9.   <\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-oswiadczenie_4 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[oswiadczenie_4]\" id=\"form-field-oswiadczenie_4\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-oswiadczenie_4\">Je d\u00e9clare consentir traitement de mes donn\u00e9es \u00e0 caract\u00e8re personnel fournies \u00e0 SCRAPO Paula Miastkowska dans ce formulaire dans le but de recevoir des documents marketing \/ commerciaux de SCRAPO Paula Miastkowska et de recevoir de SCRAPO Paula Miastkowska par voie \u00e9lectronique \u00e0 l\u2019adresse e-mail fournie dans le formulaire, des informations commerciales \/ marketing sur les activit\u00e9s de cette entit\u00e9.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-referrer_url elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[referrer_url]\" id=\"form-field-referrer_url\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-gclid elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[gclid]\" id=\"form-field-gclid\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-gad_source elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[gad_source]\" id=\"form-field-gad_source\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-gad_campaignid elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[gad_campaignid]\" id=\"form-field-gad_campaignid\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-fbclid elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[fbclid]\" id=\"form-field-fbclid\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-device_type elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[device_type]\" id=\"form-field-device_type\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-czas_wypelniania elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[czas_wypelniania]\" id=\"form-field-czas_wypelniania\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hidden elementor-field-group elementor-column elementor-field-group-miejsce_klikniecia elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"hidden\" name=\"form_fields[miejsce_klikniecia]\" id=\"form-field-miejsce_klikniecia\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text\">\n\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_126af91]\" id=\"form-field-field_126af91\" class=\"elementor-field elementor-size-sm \" style=\"display:none !important;\">\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 24 24\" width=\"512\" height=\"512\"><path d=\"M24,2V14h-2V3.414L1.457,23.957,.043,22.543,20.586,2H10V0h12c1.103,0,2,.897,2,2Z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f7f673 elementor-widget elementor-widget-html\" data-id=\"1f7f673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>document.addEventListener(\"DOMContentLoaded\", function () {\n    let categoryField = document.querySelector('select[name=\"form_fields[produkt]\"]');\n    let modelField = document.querySelector('select[name=\"form_fields[model]\"]');\n\n    let modelsByCategory = {\n        \"Presses \u00e0 balles\": [\"Z562\", \"Z603\", \"Z604\", \"Z587\", \"Z514\"],\n        \"Enrubanneuses de balles\": [\"Z561\", \"Z560\", \"Z237\", \"Z577\", \"Z593\", \"Z629 SATI EVO\", \"Z693\"],\n        \"Chargeurs\": [\"TX30\", \"T812\", \"T229\", \"T241\"],\n        \"Remorques m\u00e9langeuses\": [\"T659 OPTIMAL\", \"T659 BEL-MIX \u00e0 un rotor\", \"T659 BEL-MIX abaiss\u00e9\", \"T659 BEL-MIX \u00e0 deux rotors\", \"T705\"],\n        \"Accessoires pour chargeurs\": [\"Pinces \u00e0 balles\", \"Pinces \u00e0 balles lourdes\", \"Pince \u00e0 grumes\", \"Pince \u00e0 grumes KRAB\", \"Fourche d\u2019ensilage mod\u00e8le Q\", \"Fourche coulissante \u00e0 palettes\", \"Fourche coulissante \u00e0 palettes disposant de dents\", \"Fourche \u00e0 fumier et paille mod\u00e8le Q\", \"Fourche \u00e0 balles\", \"Godet pour mat\u00e9riaux en vrac\", \"Godet de grande capacit\u00e9\", \"Godet ouvert\", \"Godet m\u00e2choire\", \"Godet \u00e0 basculement en hauteur\", \"Godet coupe-ensilage\", \"Godet grappin\", \"L\u00e8ve-sac BIG-BAG\", \"Masse contrepoids\"],\n        \"\u00c9pandeurs \u00e0 fumier\": [\"N267 Hornet\", \"N280 Batalion\", \"N272 Taurus\", \"N272 Viking\", \"N276 Falcon\", \"N276 Falcon 2.0\", \"N277 Cerberus\"],\n        \"Remorques \u00e0 ridelles\": [\"T736\", \"T963 Nela\", \"T735\", \"T703A\", \"T957\", \"T940\", \"T710\", \"T711\", \"T711 Long\", \"T739A\", \"T739AL Long\", \"T966\", \"T730\", \"T755A\", \"T755AL Long\"],\n        \"Remorques monocoques\": [\"T930\", \"T935 TigerPower\", \"T951 TigerPower\"],\n        \"Remorques de chantier\": [\"T935\/3\"],\n        \"Remorques volum\u00e9triques \u00e0 paroi coulissante\": [\"T935\/6 LionPower\", \"T951\/6 LionPower\"],\n        \"Remorques pour balles\": [\"T954 Transporter Mini\", \"T014 Transporter Compact\", \"T009 Transporter Long\", \"T019 KP Transporter Max Expanse\", \"T019 Transporter Max Hydro-Wall\"],\n        \"Machines de travail du sol\": [\"U484\", \"U490 Novalis Trio\", \"U148\", \"U496\/83\", \"U741\/PL Long\", \"U741 Raven Light\", \"U740 Raven Opti\", \"U710 Raven Opti\", \"U786 Raven Max\", \"System Mega U910+U786\", \"System Mega U910+U457\", \"System Rhino U910+U740\/50\"],\n        \"Faucheuses\": [\"Z026 RotorCut\", \"Z011 DiskCut\", \"Z093 FrontCut\", \"Z315 RoadCut\", \"Z022 SlimCut\", \"Z022 MultiCut\", \"Z313 ProfiCut\"],\n        \"Balayeuses\": [\"T814\"],\n        \"Andaineuses\": [\"Bocian\", \"Z578\", \"Z208\"]\n    };\n\n    function updateModels() {\n        let selectedCategory = categoryField.value;\n        modelField.innerHTML = \"\"; \/\/ Wyczy\u015b\u0107 stare opcje\n\n        if (modelsByCategory[selectedCategory]) {\n            modelsByCategory[selectedCategory].forEach(function (model) {\n                let option = document.createElement(\"option\");\n                option.value = model;\n                option.textContent = model;\n                modelField.appendChild(option);\n            });\n        }\n    }\n\n    categoryField.addEventListener(\"change\", updateModels);\n});\n\n<\/script><script>jQuery(document).ready(function($) {\n    \/\/ Sprawd\u017a czy referrer istnieje\n    if (document.referrer) {\n        \/\/ Wstaw referrer do ukrytego pola o ID 'form-field-referrer_url'\n        $('#form-field-referrer_url').val(document.referrer);\n    } else {\n        \/\/ Opcjonalnie: wstaw \"Direct\", je\u015bli u\u017cytkownik wszed\u0142 bezpo\u015brednio\n        $('#form-field-referrer_url').val('Direct\/Organic');\n    }\n});\n<\/script><script>document.addEventListener('DOMContentLoaded', function() {\n    \/\/ Sprawdzamy czy to urz\u0105dzenie mobilne\n    var isMobile = \/iPhone|iPad|iPod|Android\/i.test(navigator.userAgent);\n    var deviceValue = isMobile ? \"Telefon\/Tablet\" : \"Komputer (Desktop)\";\n\n    \/\/ Znajdujemy pole formularza po ID i wpisujemy warto\u015b\u0107\n    var deviceField = document.querySelector('input[name=\"form_fields[device_type]\"]');\n    if (deviceField) {\n        deviceField.value = deviceValue;\n    }\n});\n<\/script><script>document.addEventListener('DOMContentLoaded', function() {\n    \/\/ Zapisujemy czas za\u0142adowania strony (w milisekundach)\n    var startTime = Date.now();\n\n    \/\/ Znajdujemy formularz (Elementor u\u017cywa klasy .elementor-form)\n    var form = document.querySelector('.elementor-form');\n\n    if (form) {\n        form.addEventListener('submit', function() {\n            \/\/ Obliczamy czas w sekundach\n            var endTime = Date.now();\n            var timeSpent = Math.round((endTime - startTime) \/ 1000);\n\n            \/\/ Znajdujemy ukryte pole po ID i wpisujemy wynik\n            var timeField = document.querySelector('input[name=\"form_fields[czas_wypelniania]\"]');\n            if (timeField) {\n                timeField.value = timeSpent + \" sek\";\n            }\n        });\n    }\n});\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee51736 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-heading\" data-id=\"ee51736\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">En remplissant le formulaire, vous acceptez que les donn\u00e9es personnelles fournies soient trait\u00e9es dans le but d'\u00e9tablir un contact. <a href=\"https:\/\/www.metalfach.com.pl\/fr\/clause-dinformation\/\" style=\"color:#ef3038\">D\u00e9couvrez qui traite vos donn\u00e9es et comment.<\/a> <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-feef2ee e-con-full e-flex e-con e-child\" data-id=\"feef2ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-162377b elementor-align-left cta-finance elementor-mobile-align-justify elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"162377b\" data-element_type=\"widget\" data-e-type=\"widget\" data-cta=\"Dol_Strony\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Doff_canvas%3Atoggle%26settings%3DeyJpZCI6IjJlNzJjYTciLCJkaXNwbGF5TW9kZSI6InRvZ2dsZSJ9\" id=\"cta-form-offer\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 24 24\" width=\"512\" height=\"512\"><path d=\"M24,2V14h-2V3.414L1.457,23.957,.043,22.543,20.586,2H10V0h12c1.103,0,2,.897,2,2Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Demander des informations sur le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ea7b3 elementor-align-left cta-finance elementor-mobile-align-justify elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"a7ea7b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.metalfach.com.pl\/fr\/distributeurs\/\" id=\"find_dealer\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" data-name=\"Layer 1\" viewBox=\"0 0 24 24\" width=\"512\" height=\"512\"><path d=\"M24,2V14h-2V3.414L1.457,23.957,.043,22.543,20.586,2H10V0h12c1.103,0,2,.897,2,2Z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trouver un concessionnaire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05a3fd3 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05a3fd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e5e7ab\" data-id=\"7e5e7ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f763b02 elementor-widget elementor-widget-heading\" data-id=\"f763b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Autres mod\u00e8les de notre gamme<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18502ab elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18502ab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bcb2b40\" data-id=\"bcb2b40\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4bcd17c elementor-widget elementor-widget-image\" data-id=\"4bcd17c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/produkty\/przyczepy-rolnicze\/przyczepa-rolnicza-tandem-t730\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-burtowa-t730_660x371.webp\" class=\"attachment-full size-full wp-image-62723\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-burtowa-t730_660x371.webp 660w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-burtowa-t730_660x371-480x270.webp 480w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9263d2e elementor-widget elementor-widget-heading\" data-id=\"9263d2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">T730<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-665be53 elementor-widget elementor-widget-text-editor\" data-id=\"665be53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Charge utile 8; 10; 12 T<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-69eab29\" data-id=\"69eab29\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d3e14f elementor-widget elementor-widget-image\" data-id=\"3d3e14f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/produkty\/przyczepy-rolnicze\/przyczepa-rolnicza-tandem-t755\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/burtowa-przyczepa-rolnicza-tandem-t755a_660x371.webp\" class=\"attachment-full size-full wp-image-62769\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/burtowa-przyczepa-rolnicza-tandem-t755a_660x371.webp 660w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/burtowa-przyczepa-rolnicza-tandem-t755a_660x371-480x270.webp 480w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203e570 elementor-widget elementor-widget-heading\" data-id=\"203e570\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">T755<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62e62b9 elementor-widget elementor-widget-text-editor\" data-id=\"62e62b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Charge utile 14 T<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cb41669\" data-id=\"cb41669\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-320fe7e elementor-widget elementor-widget-image\" data-id=\"320fe7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.metalfach.com.pl\/produkty\/przyczepy-rolnicze\/przyczepa-rolnicza-tandem-t755-long\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"371\" src=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-burtowa-przyczepa-rolnicza-tandem-t755al-long_660x371.webp\" class=\"attachment-full size-full wp-image-62885\" alt=\"\" srcset=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-burtowa-przyczepa-rolnicza-tandem-t755al-long_660x371.webp 660w, https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/wywrotka-burtowa-przyczepa-rolnicza-tandem-t755al-long_660x371-480x270.webp 480w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f08867f elementor-widget elementor-widget-heading\" data-id=\"f08867f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">T755AL LONG<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac705c4 elementor-widget elementor-widget-text-editor\" data-id=\"ac705c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Charge utile 14 T<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Flexibilit\u00e9 de chargement et de d\u00e9chargement T739AL Contact Contactez-nous Questions ? Nous sommes l\u00e0 pour r\u00e9pondre \u00e0 vos questions. Je d\u00e9clare consentir au traitement de mes donn\u00e9es \u00e0 caract\u00e8re personnel fournies \u00e0 METAL-FACH Sp. z o.o. dans ce formulaire afin de recevoir des documents marketing (y compris des calendriers, des gadgets publicitaires, etc.) METAL-FACH Sp. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":16552,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-69210","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Remorque agricole \u00e0 deux essieux T739 LONG - Metal-Fach<\/title>\n<meta name=\"description\" content=\"La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remorque agricole \u00e0 deux essieux T739 LONG - Metal-Fach\" \/>\n<meta property=\"og:description\" content=\"La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/\" \/>\n<meta property=\"og:site_name\" content=\"Metal-Fach\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.pl\/MetalFachOfficial\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-17T17:04:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/\",\"url\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/\",\"name\":\"Remorque agricole \u00e0 deux essieux T739 LONG - Metal-Fach\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.metalfach.com.pl\\\/wp-content\\\/uploads\\\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp\",\"datePublished\":\"2023-10-09T05:45:19+00:00\",\"dateModified\":\"2024-06-17T17:04:32+00:00\",\"description\":\"La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.metalfach.com.pl\\\/wp-content\\\/uploads\\\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp\",\"contentUrl\":\"https:\\\/\\\/www.metalfach.com.pl\\\/wp-content\\\/uploads\\\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/remorque-agricole-a-deux-essieux-t739-long\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produkty\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Remorques agricoles\",\"item\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/produits\\\/remorques-agricoles\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Remorque agricole \u00e0 deux essieux T739 LONG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/\",\"name\":\"Metal-Fach\",\"description\":\"Prasy zwijaj\u0105ce, owijarki bel, \u0142adowacze czo\u0142owe, wozy paszowe, rozrzutniki obornika, przyczepy rolnicze, agregaty uprawowe\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/#organization\",\"name\":\"Metal-Fach\",\"url\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.metalfach.com.pl\\\/wp-content\\\/uploads\\\/metalfach-logo-horizontal-r.svg\",\"contentUrl\":\"https:\\\/\\\/www.metalfach.com.pl\\\/wp-content\\\/uploads\\\/metalfach-logo-horizontal-r.svg\",\"width\":777,\"height\":207,\"caption\":\"Metal-Fach\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metalfach.com.pl\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.pl\\\/MetalFachOfficial\",\"https:\\\/\\\/www.instagram.com\\\/metalfach_official\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/metal-fach\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/metalfach1\",\"https:\\\/\\\/www.tiktok.com\\\/@metalfach_official\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remorque agricole \u00e0 deux essieux T739 LONG - Metal-Fach","description":"La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/","og_locale":"fr_FR","og_type":"article","og_title":"Remorque agricole \u00e0 deux essieux T739 LONG - Metal-Fach","og_description":"La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.","og_url":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/","og_site_name":"Metal-Fach","article_publisher":"http:\/\/www.facebook.pl\/MetalFachOfficial","article_modified_time":"2024-06-17T17:04:32+00:00","og_image":[{"url":"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/","url":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/","name":"Remorque agricole \u00e0 deux essieux T739 LONG - Metal-Fach","isPartOf":{"@id":"https:\/\/www.metalfach.com.pl\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/#primaryimage"},"image":{"@id":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/#primaryimage"},"thumbnailUrl":"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp","datePublished":"2023-10-09T05:45:19+00:00","dateModified":"2024-06-17T17:04:32+00:00","description":"La remorque \u00e0 ridelles T739AL repr\u00e9sente la nouvelle g\u00e9n\u00e9ration de notre benne \u00e0 bascule T739A qui a fait ses preuves. Ses ridelles non divis\u00e9es permettent une plus grande flexibilit\u00e9 dans le chargement et le d\u00e9chargement en \u00e9liminant le poteau central. Les ridelles sont renforc\u00e9s par des profil\u00e9s.","breadcrumb":{"@id":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/#primaryimage","url":"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp","contentUrl":"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/przyczepa-rolnicza-dwuosiowa-wywrotka-t739al-long_660x371.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/remorque-agricole-a-deux-essieux-t739-long\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.metalfach.com.pl\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.metalfach.com.pl\/fr\/produkty\/"},{"@type":"ListItem","position":3,"name":"Remorques agricoles","item":"https:\/\/www.metalfach.com.pl\/fr\/produits\/remorques-agricoles\/"},{"@type":"ListItem","position":4,"name":"Remorque agricole \u00e0 deux essieux T739 LONG"}]},{"@type":"WebSite","@id":"https:\/\/www.metalfach.com.pl\/fr\/#website","url":"https:\/\/www.metalfach.com.pl\/fr\/","name":"Metal-Fach","description":"Prasy zwijaj\u0105ce, owijarki bel, \u0142adowacze czo\u0142owe, wozy paszowe, rozrzutniki obornika, przyczepy rolnicze, agregaty uprawowe","publisher":{"@id":"https:\/\/www.metalfach.com.pl\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metalfach.com.pl\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.metalfach.com.pl\/fr\/#organization","name":"Metal-Fach","url":"https:\/\/www.metalfach.com.pl\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.metalfach.com.pl\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/metalfach-logo-horizontal-r.svg","contentUrl":"https:\/\/www.metalfach.com.pl\/wp-content\/uploads\/metalfach-logo-horizontal-r.svg","width":777,"height":207,"caption":"Metal-Fach"},"image":{"@id":"https:\/\/www.metalfach.com.pl\/fr\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.pl\/MetalFachOfficial","https:\/\/www.instagram.com\/metalfach_official\/","https:\/\/www.linkedin.com\/company\/metal-fach","https:\/\/www.youtube.com\/user\/metalfach1","https:\/\/www.tiktok.com\/@metalfach_official"]}]}},"_links":{"self":[{"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/pages\/69210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/comments?post=69210"}],"version-history":[{"count":0,"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/pages\/69210\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/pages\/16552"}],"wp:attachment":[{"href":"https:\/\/www.metalfach.com.pl\/fr\/wp-json\/wp\/v2\/media?parent=69210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}